{"id":3448,"date":"2022-07-21T02:34:56","date_gmt":"2022-07-21T00:34:56","guid":{"rendered":"http:\/\/unicoach.wgl-demo.net\/?page_id=3448"},"modified":"2026-03-05T18:46:08","modified_gmt":"2026-03-05T17:46:08","slug":"diplomado","status":"publish","type":"page","link":"https:\/\/maguiblock.com\/en\/diplomado\/","title":{"rendered":"Diploma"},"content":{"rendered":"<style>.kb-row-layout-id3448_41cdba-61 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3448_41cdba-61 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3448_41cdba-61 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 2000px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:200px;padding-bottom:90px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3448_41cdba-61{background-image:url('https:\/\/maguiblock.com\/wp-content\/uploads\/2026\/01\/Frame-1-1-2.webp');background-size:cover;background-position:center center;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id3448_41cdba-61 > .kt-row-layout-overlay{opacity:0.70;background-color:var(--global-palette8, #F7FAFC);}@media all and (max-width: 1024px){.kb-row-layout-id3448_41cdba-61 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3448_41cdba-61 > .kt-row-column-wrap{padding-top:150px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3448_41cdba-61 alignnone kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3448_206b15-2f > .kt-inside-inner-col,.kadence-column3448_206b15-2f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3448_206b15-2f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3448_206b15-2f > .kt-inside-inner-col{flex-direction:column;}.kadence-column3448_206b15-2f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3448_206b15-2f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3448_206b15-2f{position:relative;}@media all and (max-width: 1024px){.kadence-column3448_206b15-2f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3448_206b15-2f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3448_206b15-2f\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3448_5577a8-25, .wp-block-kadence-advancedheading.kt-adv-heading3448_5577a8-25[data-kb-block=\"kb-adv-heading3448_5577a8-25\"]{text-align:center;font-size:65px;font-weight:800;font-style:normal;font-family:'Abhaya Libre';}.wp-block-kadence-advancedheading.kt-adv-heading3448_5577a8-25 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3448_5577a8-25[data-kb-block=\"kb-adv-heading3448_5577a8-25\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3448_5577a8-25 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3448_5577a8-25[data-kb-block=\"kb-adv-heading3448_5577a8-25\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading3448_5577a8-25, .wp-block-kadence-advancedheading.kt-adv-heading3448_5577a8-25[data-kb-block=\"kb-adv-heading3448_5577a8-25\"]{font-size:45px;}}<\/style>\n<h2 class=\"kt-adv-heading3448_5577a8-25 wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading3448_5577a8-25\">Diplomado<\/h2>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3448_865c24-ce > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3448_865c24-ce > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3448_865c24-ce > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1200px;margin-left:auto;margin-right:auto;padding-top:100px;padding-bottom:24px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id3448_865c24-ce > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3448_865c24-ce > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id3448_865c24-ce > .kt-row-column-wrap{padding-top:50px;padding-right:30px;padding-bottom:50px;padding-left:30px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3448_865c24-ce alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3448_200596-65 > .kt-inside-inner-col,.kadence-column3448_200596-65 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3448_200596-65 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3448_200596-65 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3448_200596-65 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3448_200596-65 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3448_200596-65{position:relative;}@media all and (max-width: 1024px){.kadence-column3448_200596-65 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3448_200596-65 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3448_200596-65\" data-aos=\"fade-left\" data-aos-duration=\"2000\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3448_3fd268-ce, .wp-block-kadence-advancedheading.kt-adv-heading3448_3fd268-ce[data-kb-block=\"kb-adv-heading3448_3fd268-ce\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3448_3fd268-ce mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3448_3fd268-ce[data-kb-block=\"kb-adv-heading3448_3fd268-ce\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3448_3fd268-ce img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3448_3fd268-ce[data-kb-block=\"kb-adv-heading3448_3fd268-ce\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h1 class=\"kt-adv-heading3448_3fd268-ce wp-block-kadence-advancedheading has-theme-palette-8-color has-text-color\" data-kb-block=\"kb-adv-heading3448_3fd268-ce\">Diplomado en sistemas familiares<\/h1>\n\n\n<style>.kb-image3448_7d45cd-40 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:15px;border-top-right-radius:15px;border-bottom-right-radius:15px;border-bottom-left-radius:15px;}.kb-image3448_7d45cd-40 img.kb-img, .kb-image3448_7d45cd-40 .kb-img img{border-top-left-radius:15px;border-top-right-radius:15px;border-bottom-right-radius:15px;border-bottom-left-radius:15px;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image3448_7d45cd-40 size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1006\" src=\"https:\/\/maguiblock.com\/wp-content\/uploads\/2022\/06\/Imagen-Magui-2_1200-x-1006-px.jpg\" alt=\"\" class=\"kb-img wp-image-29195\" srcset=\"https:\/\/maguiblock.com\/wp-content\/uploads\/2022\/06\/Imagen-Magui-2_1200-x-1006-px.jpg 1200w, https:\/\/maguiblock.com\/wp-content\/uploads\/2022\/06\/Imagen-Magui-2_1200-x-1006-px-600x503.jpg 600w, https:\/\/maguiblock.com\/wp-content\/uploads\/2022\/06\/Imagen-Magui-2_1200-x-1006-px-768x644.jpg 768w, https:\/\/maguiblock.com\/wp-content\/uploads\/2022\/06\/Imagen-Magui-2_1200-x-1006-px-1140x956.jpg 1140w, https:\/\/maguiblock.com\/wp-content\/uploads\/2022\/06\/Imagen-Magui-2_1200-x-1006-px-107x90.jpg 107w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column3448_eb214c-38 > .kt-inside-inner-col{padding-top:80px;padding-right:40px;padding-bottom:80px;padding-left:60px;}.kadence-column3448_eb214c-38 > .kt-inside-inner-col{box-shadow:0px 0px 14px 0px rgba(0, 0, 0, 0.2);}.kadence-column3448_eb214c-38 > .kt-inside-inner-col,.kadence-column3448_eb214c-38 > .kt-inside-inner-col:before{border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;}.kadence-column3448_eb214c-38 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3448_eb214c-38 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3448_eb214c-38 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3448_eb214c-38 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column3448_eb214c-38 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3448_eb214c-38{position:relative;}.kadence-column3448_eb214c-38, .kt-inside-inner-col > .kadence-column3448_eb214c-38:not(.specificity){margin-top:80px;margin-right:100px;margin-left:-100px;}@media all and (max-width: 1024px){.kadence-column3448_eb214c-38 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3448_eb214c-38 > .kt-inside-inner-col{padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;flex-direction:column;justify-content:center;}.kadence-column3448_eb214c-38, .kt-inside-inner-col > .kadence-column3448_eb214c-38:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3448_eb214c-38\" data-aos=\"fade-right\" data-aos-duration=\"2000\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns3448_e444de-7a{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns3448_e444de-7a .kt-button{font-weight:normal;font-style:normal;}.kt-btns3448_e444de-7a .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns3448_e444de-7a .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns3448_e444de-7a .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns3448_e444de-7a .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns3448_e444de-7a .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns3448_e444de-7a .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns3448_e444de-7a .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns3448_e444de-7a\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn3448_41dd18-dd.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn3448_41dd18-dd.kb-button{color:var(--global-palette7, #EDF2F7);background:var(--global-palette9, #ffffff);font-size:13px;font-family:Roboto;font-weight:500;text-transform:uppercase;border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;box-shadow:1px 1px 2px 0px rgba(0, 0, 0, 0.2);}.kb-btn3448_41dd18-dd.kb-button .kb-svg-icon-wrap{color:#87cbb1;padding-bottom:2px;}.wp-block-kadence-advancedbtn .kb-btn3448_41dd18-dd.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn3448_41dd18-dd.kb-button:focus{color:var(--global-palette7, #EDF2F7);background:var(--global-palette9, #ffffff);}<\/style><span class=\"kb-button kt-button button kb-btn3448_41dd18-dd kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill  kt-btn-has-text-true kt-btn-has-svg-true  wp-block-kadence-singlebtn\"><span class=\"kb-svg-icon-wrap kb-svg-icon-ic_record kt-btn-icon-side-left\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M3 0c-1.66 0-3 1.34-3 3s1.34 3 3 3 3-1.34 3-3-1.34-3-3-3z\" transform=\"translate(1 1)\"\/><\/svg><\/span><span class=\"kt-btn-inner-text\"><strong><strong>Diplomado<\/strong><\/strong><\/span><\/span><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3448_8f4a31-37, .wp-block-kadence-advancedheading.kt-adv-heading3448_8f4a31-37[data-kb-block=\"kb-adv-heading3448_8f4a31-37\"]{margin-top:-20px;font-size:36px;font-weight:400;font-style:normal;font-family:Roboto;}.wp-block-kadence-advancedheading.kt-adv-heading3448_8f4a31-37 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3448_8f4a31-37[data-kb-block=\"kb-adv-heading3448_8f4a31-37\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3448_8f4a31-37 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3448_8f4a31-37[data-kb-block=\"kb-adv-heading3448_8f4a31-37\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading3448_8f4a31-37 wp-block-kadence-advancedheading has-theme-palette-8-color has-text-color\" data-kb-block=\"kb-adv-heading3448_8f4a31-37\">Convi\u00e9rtete en Coach certificado del m\u00e9todo Magui Block\u00ae<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3448_e90c8f-6a, .wp-block-kadence-advancedheading.kt-adv-heading3448_e90c8f-6a[data-kb-block=\"kb-adv-heading3448_e90c8f-6a\"]{padding-right:0px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3448_e90c8f-6a mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3448_e90c8f-6a[data-kb-block=\"kb-adv-heading3448_e90c8f-6a\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3448_e90c8f-6a img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3448_e90c8f-6a[data-kb-block=\"kb-adv-heading3448_e90c8f-6a\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading3448_e90c8f-6a wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3448_e90c8f-6a\">\u00a1Hola ser de luz!<br>Te ofrezco el&nbsp;<strong>diplomado en Sistemas Familiares<\/strong>, con el que aprender\u00e1s el poderoso&nbsp;<strong>m\u00e9todo Magui Block\u00ae<\/strong>, que incluye las&nbsp;<strong>t\u00e9cnicas m\u00e1s avanzadas en psicoterapia<\/strong>, combinadas de una manera \u00fanica para lograr resultados efectivos en un tiempo extraordinario.<br>Muchas gracias por tu inter\u00e9s en entrenarte como coach en el m\u00e9todo Magui Block\u00ae<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3448_e2af95-da > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3448_e2af95-da > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3448_e2af95-da > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1100px;margin-left:auto;margin-right:auto;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3448_e2af95-da > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3448_e2af95-da > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3448_e2af95-da > .kt-row-column-wrap{padding-right:30px;padding-left:30px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3448_e2af95-da alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3448_590707-38 > .kt-inside-inner-col,.kadence-column3448_590707-38 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3448_590707-38 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3448_590707-38 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3448_590707-38 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3448_590707-38 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3448_590707-38{position:relative;}@media all and (max-width: 1024px){.kadence-column3448_590707-38 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3448_590707-38 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3448_590707-38\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3448_fcbe45-b1, .wp-block-kadence-advancedheading.kt-adv-heading3448_fcbe45-b1[data-kb-block=\"kb-adv-heading3448_fcbe45-b1\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3448_fcbe45-b1 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3448_fcbe45-b1[data-kb-block=\"kb-adv-heading3448_fcbe45-b1\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3448_fcbe45-b1 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3448_fcbe45-b1[data-kb-block=\"kb-adv-heading3448_fcbe45-b1\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h1 class=\"kt-adv-heading3448_fcbe45-b1 wp-block-kadence-advancedheading has-theme-palette-8-color has-text-color\" data-kb-block=\"kb-adv-heading3448_fcbe45-b1\">\u00bfC\u00f3mo sabes si el diplomado en Sistemas Familiares es para ti?<\/h1>\n\n\n\n<p><br>Estas preguntas pueden ayudarte:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00bfAnhelas hacer un trabajo significativo que sea profundamente gratificante y que genere m\u00e1s amor en el mundo?<\/li>\n\n\n\n<li>\u00bfEst\u00e1s buscando una carrera financieramente lucrativa ayudando a las personas a liberarse de aquello que les estorba para ser felices?<\/li>\n\n\n\n<li>\u00bfSientes la necesidad de realizar cambios que te impulsen hacia tu siguiente nivel profesional y evolutivo?<\/li>\n<\/ul>\n\n\n\n<p>Si respondiste&nbsp;<strong>\u00a1S\u00ed!<\/strong>&nbsp;a cualquier de ellas, tu coraz\u00f3n y tu cabeza te llaman a convertirte en&nbsp;<strong>coach certificado del m\u00e9todo Magui Block\u00ae.<\/strong><\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3448_f3db77-af > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3448_f3db77-af > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3448_f3db77-af > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1100px;margin-left:auto;margin-right:auto;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3448_f3db77-af > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3448_f3db77-af > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3448_f3db77-af > .kt-row-column-wrap{padding-right:30px;padding-left:30px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3448_f3db77-af alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3448_6a8f78-60 > .kt-inside-inner-col,.kadence-column3448_6a8f78-60 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3448_6a8f78-60 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3448_6a8f78-60 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3448_6a8f78-60 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3448_6a8f78-60 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3448_6a8f78-60{position:relative;}@media all and (max-width: 1024px){.kadence-column3448_6a8f78-60 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3448_6a8f78-60 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3448_6a8f78-60\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns3448_346a40-75{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns3448_346a40-75 .kt-button{font-weight:normal;font-style:normal;}.kt-btns3448_346a40-75 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns3448_346a40-75 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns3448_346a40-75 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns3448_346a40-75 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns3448_346a40-75 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns3448_346a40-75 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns3448_346a40-75 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns3448_346a40-75\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn3448_e02382-23.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn3448_e02382-23.kb-button{color:var(--global-palette7, #EDF2F7);background:var(--global-palette9, #ffffff);font-size:13px;font-family:Roboto;font-weight:500;text-transform:uppercase;border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;box-shadow:1px 1px 2px 0px rgba(0, 0, 0, 0.2);}.kb-btn3448_e02382-23.kb-button .kb-svg-icon-wrap{color:#87cbb1;padding-bottom:2px;}.wp-block-kadence-advancedbtn .kb-btn3448_e02382-23.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn3448_e02382-23.kb-button:focus{color:var(--global-palette7, #EDF2F7);background:var(--global-palette9, #ffffff);}<\/style><span class=\"kb-button kt-button button kb-btn3448_e02382-23 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill  kt-btn-has-text-true kt-btn-has-svg-true  wp-block-kadence-singlebtn\"><span class=\"kb-svg-icon-wrap kb-svg-icon-ic_record kt-btn-icon-side-left\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M3 0c-1.66 0-3 1.34-3 3s1.34 3 3 3 3-1.34 3-3-1.34-3-3-3z\" transform=\"translate(1 1)\"\/><\/svg><\/span><span class=\"kt-btn-inner-text\"><strong><strong><strong>Diplomado en sistemas familiares<\/strong><\/strong><\/strong><\/span><\/span><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3448_1e2a49-12, .wp-block-kadence-advancedheading.kt-adv-heading3448_1e2a49-12[data-kb-block=\"kb-adv-heading3448_1e2a49-12\"]{margin-top:-20px;font-size:36px;font-weight:400;font-style:normal;font-family:Roboto;}.wp-block-kadence-advancedheading.kt-adv-heading3448_1e2a49-12 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3448_1e2a49-12[data-kb-block=\"kb-adv-heading3448_1e2a49-12\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3448_1e2a49-12 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3448_1e2a49-12[data-kb-block=\"kb-adv-heading3448_1e2a49-12\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h1 class=\"kt-adv-heading3448_1e2a49-12 wp-block-kadence-advancedheading has-theme-palette-8-color has-text-color\" data-kb-block=\"kb-adv-heading3448_1e2a49-12\">Cr\u00e9ate una carrera \u00fatil y pr\u00f3spera apoyando a los dem\u00e1s a transformarse<\/h1>\n\n\n<style>.kb-row-layout-id3448_932a18-8e > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3448_932a18-8e > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3448_932a18-8e > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);}.kb-row-layout-id3448_932a18-8e > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id3448_932a18-8e > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}.kb-row-layout-id3448_932a18-8e > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3448_932a18-8e > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id3448_932a18-8e > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id3448_932a18-8e > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id3448_932a18-8e > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3448_932a18-8e alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3448_3cc9d8-89 > .kt-inside-inner-col,.kadence-column3448_3cc9d8-89 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3448_3cc9d8-89 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3448_3cc9d8-89 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3448_3cc9d8-89 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3448_3cc9d8-89 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3448_3cc9d8-89{position:relative;}@media all and (max-width: 1024px){.kadence-column3448_3cc9d8-89 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3448_3cc9d8-89 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3448_3cc9d8-89\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box3448_7259e4-dd .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box3448_7259e4-dd .kt-blocks-info-box-link-wrap{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;background:var(--global-palette9, #ffffff);padding-top:40px;padding-right:40px;padding-bottom:60px;padding-left:40px;}.kt-info-box3448_7259e4-dd .kt-blocks-info-box-link-wrap:hover{background:var(--global-palette7, #EDF2F7);}.kt-info-box3448_7259e4-dd .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box3448_7259e4-dd .kt-info-svg-icon-flip, .kt-info-box3448_7259e4-dd .kt-blocks-info-box-number{font-size:40px;}.kt-info-box3448_7259e4-dd .kt-blocks-info-box-media{color:#87cbb1;background:#edf2ff;border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:13px;padding-right:13px;padding-bottom:13px;padding-left:13px;}.kt-info-box3448_7259e4-dd .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:16px;margin-left:0px;}.kt-info-box3448_7259e4-dd .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box3448_7259e4-dd .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette7, #EDF2F7);background:var(--global-palette9, #ffffff);}.kt-info-box3448_7259e4-dd .kt-infobox-textcontent h4.kt-blocks-info-box-title{color:var(--global-palette8, #F7FAFC);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box3448_7259e4-dd .kt-blocks-info-box-link-wrap:hover h4.kt-blocks-info-box-title{color:var(--global-palette9, #ffffff);}.kt-info-box3448_7259e4-dd .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette7, #EDF2F7);}.kt-info-box3448_7259e4-dd .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette9, #ffffff);}.kt-info-box3448_7259e4-dd .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box3448_7259e4-dd .kt-blocks-info-box-link-wrap{box-shadow:5px 5px 5px 5px rgba(0, 0, 0, 0.15);}.kt-info-box3448_7259e4-dd .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(0, 0, 0, 0.2);}@media all and (max-width: 1024px){.kt-info-box3448_7259e4-dd .kt-blocks-info-box-link-wrap{box-shadow:5px 5px 5px 5px rgba(0, 0, 0, 0.15);}}@media all and (max-width: 1024px){.kt-info-box3448_7259e4-dd .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(0, 0, 0, 0.2);}}@media all and (max-width: 767px){.kt-info-box3448_7259e4-dd .kt-blocks-info-box-link-wrap{box-shadow:5px 5px 5px 5px rgba(0, 0, 0, 0.15);}.kt-info-box3448_7259e4-dd .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(0, 0, 0, 0.2);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box3448_7259e4-dd\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_heart kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M20.84 4.61a5.5 5.5 0 0 0-7.78 0L12 5.67l-1.06-1.06a5.5 5.5 0 0 0-7.78 7.78l1.06 1.06L12 21.23l7.78-7.78 1.06-1.06a5.5 5.5 0 0 0 0-7.78z\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h4 class=\"kt-blocks-info-box-title\">Genera amor<\/h4><p class=\"kt-blocks-info-box-text\">Realiza un trabajo significativo que sea profundamente gratificante y que genere m\u00e1s amor en el mundo.<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3448_f97c50-84 > .kt-inside-inner-col,.kadence-column3448_f97c50-84 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3448_f97c50-84 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3448_f97c50-84 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3448_f97c50-84 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3448_f97c50-84 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3448_f97c50-84{position:relative;}@media all and (max-width: 1024px){.kadence-column3448_f97c50-84 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3448_f97c50-84 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3448_f97c50-84\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box3448_baeac5-52 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box3448_baeac5-52 .kt-blocks-info-box-link-wrap{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;background:var(--global-palette9, #ffffff);padding-top:40px;padding-right:40px;padding-bottom:60px;padding-left:40px;}.kt-info-box3448_baeac5-52 .kt-blocks-info-box-link-wrap:hover{background:var(--global-palette7, #EDF2F7);}.kt-info-box3448_baeac5-52 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box3448_baeac5-52 .kt-info-svg-icon-flip, .kt-info-box3448_baeac5-52 .kt-blocks-info-box-number{font-size:40px;}.kt-info-box3448_baeac5-52 .kt-blocks-info-box-media{color:#87cbb1;background:#edf2ff;border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:13px;padding-right:13px;padding-bottom:13px;padding-left:13px;}.kt-info-box3448_baeac5-52 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:16px;margin-left:0px;}.kt-info-box3448_baeac5-52 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box3448_baeac5-52 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette7, #EDF2F7);background:var(--global-palette9, #ffffff);}.kt-info-box3448_baeac5-52 .kt-infobox-textcontent h4.kt-blocks-info-box-title{color:var(--global-palette8, #F7FAFC);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box3448_baeac5-52 .kt-blocks-info-box-link-wrap:hover h4.kt-blocks-info-box-title{color:var(--global-palette9, #ffffff);}.kt-info-box3448_baeac5-52 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette7, #EDF2F7);}.kt-info-box3448_baeac5-52 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette9, #ffffff);}.kt-info-box3448_baeac5-52 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box3448_baeac5-52 .kt-blocks-info-box-link-wrap{box-shadow:5px 5px 5px 5px rgba(0, 0, 0, 0.15);}.kt-info-box3448_baeac5-52 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(0, 0, 0, 0.2);}@media all and (max-width: 1024px){.kt-info-box3448_baeac5-52 .kt-blocks-info-box-link-wrap{box-shadow:5px 5px 5px 5px rgba(0, 0, 0, 0.15);}}@media all and (max-width: 1024px){.kt-info-box3448_baeac5-52 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(0, 0, 0, 0.2);}}@media all and (max-width: 767px){.kt-info-box3448_baeac5-52 .kt-blocks-info-box-link-wrap{box-shadow:5px 5px 5px 5px rgba(0, 0, 0, 0.15);}.kt-info-box3448_baeac5-52 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(0, 0, 0, 0.2);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box3448_baeac5-52\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_star kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polygon points=\"12 2 15.09 8.26 22 9.27 17 14.14 18.18 21.02 12 17.77 5.82 21.02 7 14.14 2 9.27 8.91 8.26 12 2\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h4 class=\"kt-blocks-info-box-title\">Ayuda a los dem\u00e1s<\/h4><p class=\"kt-blocks-info-box-text\">Inicia una carrera rentable ayudando a las personas a liberarse de aquello que les estorba para ser felices.<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3448_b1bb41-1e > .kt-inside-inner-col,.kadence-column3448_b1bb41-1e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3448_b1bb41-1e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3448_b1bb41-1e > .kt-inside-inner-col{flex-direction:column;}.kadence-column3448_b1bb41-1e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3448_b1bb41-1e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3448_b1bb41-1e{position:relative;}@media all and (max-width: 1024px){.kadence-column3448_b1bb41-1e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3448_b1bb41-1e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3448_b1bb41-1e\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box3448_d98d7a-3f .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box3448_d98d7a-3f .kt-blocks-info-box-link-wrap{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;background:var(--global-palette9, #ffffff);padding-top:40px;padding-right:40px;padding-bottom:60px;padding-left:40px;}.kt-info-box3448_d98d7a-3f .kt-blocks-info-box-link-wrap:hover{background:var(--global-palette7, #EDF2F7);}.kt-info-box3448_d98d7a-3f .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box3448_d98d7a-3f .kt-info-svg-icon-flip, .kt-info-box3448_d98d7a-3f .kt-blocks-info-box-number{font-size:40px;}.kt-info-box3448_d98d7a-3f .kt-blocks-info-box-media{color:#87cbb1;background:#edf2ff;border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:13px;padding-right:13px;padding-bottom:13px;padding-left:13px;}.kt-info-box3448_d98d7a-3f .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:16px;margin-left:0px;}.kt-info-box3448_d98d7a-3f .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box3448_d98d7a-3f .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette7, #EDF2F7);background:var(--global-palette9, #ffffff);}.kt-info-box3448_d98d7a-3f .kt-infobox-textcontent h4.kt-blocks-info-box-title{color:var(--global-palette8, #F7FAFC);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box3448_d98d7a-3f .kt-blocks-info-box-link-wrap:hover h4.kt-blocks-info-box-title{color:var(--global-palette9, #ffffff);}.kt-info-box3448_d98d7a-3f .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette7, #EDF2F7);}.kt-info-box3448_d98d7a-3f .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette9, #ffffff);}.kt-info-box3448_d98d7a-3f .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box3448_d98d7a-3f .kt-blocks-info-box-link-wrap{box-shadow:5px 5px 5px 5px rgba(0, 0, 0, 0.15);}.kt-info-box3448_d98d7a-3f .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(0, 0, 0, 0.2);}@media all and (max-width: 1024px){.kt-info-box3448_d98d7a-3f .kt-blocks-info-box-link-wrap{box-shadow:5px 5px 5px 5px rgba(0, 0, 0, 0.15);}}@media all and (max-width: 1024px){.kt-info-box3448_d98d7a-3f .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(0, 0, 0, 0.2);}}@media all and (max-width: 767px){.kt-info-box3448_d98d7a-3f .kt-blocks-info-box-link-wrap{box-shadow:5px 5px 5px 5px rgba(0, 0, 0, 0.15);}.kt-info-box3448_d98d7a-3f .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(0, 0, 0, 0.2);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box3448_d98d7a-3f\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_gem kt-info-svg-icon\"><svg viewBox=\"0 0 576 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M485.5 0L576 160H474.9L405.7 0h79.8zm-128 0l69.2 160H149.3L218.5 0h139zm-267 0h79.8l-69.2 160H0L90.5 0zM0 192h100.7l123 251.7c1.5 3.1-2.7 5.9-5 3.3L0 192zm148.2 0h279.6l-137 318.2c-1 2.4-4.5 2.4-5.5 0L148.2 192zm204.1 251.7l123-251.7H576L357.3 446.9c-2.3 2.7-6.5-.1-5-3.2z\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h4 class=\"kt-blocks-info-box-title\">Sup\u00e9rate<\/h4><p class=\"kt-blocks-info-box-text\">Realiza cambios que te impulsen hacia tu siguiente nivel profesional a la vez que te transformas con amor.<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3448_1d03d7-a1 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3448_1d03d7-a1 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3448_1d03d7-a1 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1100px;margin-left:auto;margin-right:auto;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3448_1d03d7-a1 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3448_1d03d7-a1 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3448_1d03d7-a1 > .kt-row-column-wrap{padding-right:30px;padding-left:30px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3448_1d03d7-a1 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3448_3f9291-af > .kt-inside-inner-col,.kadence-column3448_3f9291-af > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3448_3f9291-af > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3448_3f9291-af > .kt-inside-inner-col{flex-direction:column;}.kadence-column3448_3f9291-af > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3448_3f9291-af > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3448_3f9291-af{position:relative;}@media all and (max-width: 1024px){.kadence-column3448_3f9291-af > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3448_3f9291-af > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3448_3f9291-af\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3448_14a0a5-cd, .wp-block-kadence-advancedheading.kt-adv-heading3448_14a0a5-cd[data-kb-block=\"kb-adv-heading3448_14a0a5-cd\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3448_14a0a5-cd mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3448_14a0a5-cd[data-kb-block=\"kb-adv-heading3448_14a0a5-cd\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3448_14a0a5-cd img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3448_14a0a5-cd[data-kb-block=\"kb-adv-heading3448_14a0a5-cd\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h1 class=\"kt-adv-heading3448_14a0a5-cd wp-block-kadence-advancedheading has-theme-palette-8-color has-text-color\" data-kb-block=\"kb-adv-heading3448_14a0a5-cd\">\u00bfPor qu\u00e9 te conviene estudiar conmigo?<\/h1>\n\n\n\n<p><br>Tengo m\u00e1s de 30 a\u00f1os de experiencia cl\u00ednica, una pr\u00e1ctica abundante y miles de consultantes que han transformado sus vidas positivamente. Adem\u00e1s, tengo m\u00e1s de 15 a\u00f1os capacitando profesionalmente a terapeutas y existen cientos de alumnos utilizando las herramientas que les he ense\u00f1ado para ayudar a m\u00e1s personas a ser felices.<\/p>\n\n\n\n<p>En el Diplomado en Sistemas Familiares aprendes mi poderoso m\u00e9todo que incluye las t\u00e9cnicas m\u00e1s avanzadas en psicoterapia,&nbsp;<a href=\"https:\/\/maguiblock.com\/constelacion-familiar\/\">constelaciones familiares<\/a>, hipnosis Ericksoniana, Gestalt y t\u00e9cnicas de procesamiento acelerado, combinadas de una manera \u00fanica, para lograr resultados efectivos en un tiempo extraordinario.<\/p>\n\n\n<style>.kb-image3448_d1e81d-c5.kb-image-is-ratio-size, .kb-image3448_d1e81d-c5 .kb-image-is-ratio-size{max-width:304px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image3448_d1e81d-c5.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image3448_d1e81d-c5 .kb-image-is-ratio-size{align-self:unset;}.kb-image3448_d1e81d-c5 figure{max-width:304px;}.kb-image3448_d1e81d-c5 .image-is-svg, .kb-image3448_d1e81d-c5 .image-is-svg img{width:100%;}.kb-image3448_d1e81d-c5 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image3448_d1e81d-c5\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/maguiblock.com\/wp-content\/uploads\/2024\/10\/Untitled-design-5.jpg\" alt=\"\" class=\"kb-img wp-image-38355\" srcset=\"https:\/\/maguiblock.com\/wp-content\/uploads\/2024\/10\/Untitled-design-5.jpg 600w, https:\/\/maguiblock.com\/wp-content\/uploads\/2024\/10\/Untitled-design-5-300x300.jpg 300w, https:\/\/maguiblock.com\/wp-content\/uploads\/2024\/10\/Untitled-design-5-100x100.jpg 100w, https:\/\/maguiblock.com\/wp-content\/uploads\/2024\/10\/Untitled-design-5-150x150.jpg 150w, https:\/\/maguiblock.com\/wp-content\/uploads\/2024\/10\/Untitled-design-5-90x90.jpg 90w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3448_040d0a-00 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3448_040d0a-00 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3448_040d0a-00 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1100px;margin-left:auto;margin-right:auto;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3448_040d0a-00 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3448_040d0a-00 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3448_040d0a-00 > .kt-row-column-wrap{padding-right:30px;padding-left:30px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3448_040d0a-00 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3448_168693-64 > .kt-inside-inner-col,.kadence-column3448_168693-64 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3448_168693-64 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3448_168693-64 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3448_168693-64 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3448_168693-64 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3448_168693-64{position:relative;}@media all and (max-width: 1024px){.kadence-column3448_168693-64 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3448_168693-64 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3448_168693-64\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3448_06860d-45, .wp-block-kadence-advancedheading.kt-adv-heading3448_06860d-45[data-kb-block=\"kb-adv-heading3448_06860d-45\"]{margin-top:-20px;text-align:center;font-size:36px;font-weight:400;font-style:normal;font-family:Roboto;}.wp-block-kadence-advancedheading.kt-adv-heading3448_06860d-45 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3448_06860d-45[data-kb-block=\"kb-adv-heading3448_06860d-45\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3448_06860d-45 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3448_06860d-45[data-kb-block=\"kb-adv-heading3448_06860d-45\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h1 class=\"kt-adv-heading3448_06860d-45 wp-block-kadence-advancedheading has-theme-palette-8-color has-text-color\" data-kb-block=\"kb-adv-heading3448_06860d-45\">\u00bfQu\u00e9 requisitos se necesitan para estudiarlo?<\/h1>\n\n\n<style>.kb-row-layout-id3448_4866f3-d9 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3448_4866f3-d9 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3448_4866f3-d9 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);}.kb-row-layout-id3448_4866f3-d9 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id3448_4866f3-d9 > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}.kb-row-layout-id3448_4866f3-d9 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3448_4866f3-d9 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id3448_4866f3-d9 > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id3448_4866f3-d9 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id3448_4866f3-d9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3448_4866f3-d9 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3448_c08941-9a > .kt-inside-inner-col,.kadence-column3448_c08941-9a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3448_c08941-9a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3448_c08941-9a > .kt-inside-inner-col{flex-direction:column;}.kadence-column3448_c08941-9a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3448_c08941-9a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3448_c08941-9a{position:relative;}@media all and (max-width: 1024px){.kadence-column3448_c08941-9a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3448_c08941-9a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3448_c08941-9a\"><div class=\"kt-inside-inner-col\">\n<p class=\"has-text-align-center\">1. Ser saludable psicol\u00f3gica y emocionalmente para poder acompa\u00f1ar a otras personas en su proceso de transformaci\u00f3n.<\/p>\n\n\n<style>.kb-image3448_bf4862-db .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image3448_bf4862-db size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/maguiblock.com\/wp-content\/uploads\/2024\/10\/Untitled-design-9.jpg\" alt=\"\" class=\"kb-img wp-image-38357\" srcset=\"https:\/\/maguiblock.com\/wp-content\/uploads\/2024\/10\/Untitled-design-9.jpg 600w, https:\/\/maguiblock.com\/wp-content\/uploads\/2024\/10\/Untitled-design-9-300x300.jpg 300w, https:\/\/maguiblock.com\/wp-content\/uploads\/2024\/10\/Untitled-design-9-100x100.jpg 100w, https:\/\/maguiblock.com\/wp-content\/uploads\/2024\/10\/Untitled-design-9-150x150.jpg 150w, https:\/\/maguiblock.com\/wp-content\/uploads\/2024\/10\/Untitled-design-9-90x90.jpg 90w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column3448_7d3287-00 > .kt-inside-inner-col,.kadence-column3448_7d3287-00 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3448_7d3287-00 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3448_7d3287-00 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3448_7d3287-00 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3448_7d3287-00 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3448_7d3287-00{position:relative;}@media all and (max-width: 1024px){.kadence-column3448_7d3287-00 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3448_7d3287-00 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3448_7d3287-00\"><div class=\"kt-inside-inner-col\">\n<p class=\"has-text-align-center\">2. Leer y escribir con fluidez.<br><br><br><br><\/p>\n\n\n<style>.kb-image3448_7d0b2c-cf .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image3448_7d0b2c-cf size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/maguiblock.com\/wp-content\/uploads\/2024\/10\/Untitled-design-7.jpg\" alt=\"\" class=\"kb-img wp-image-38359\" srcset=\"https:\/\/maguiblock.com\/wp-content\/uploads\/2024\/10\/Untitled-design-7.jpg 600w, https:\/\/maguiblock.com\/wp-content\/uploads\/2024\/10\/Untitled-design-7-300x300.jpg 300w, https:\/\/maguiblock.com\/wp-content\/uploads\/2024\/10\/Untitled-design-7-100x100.jpg 100w, https:\/\/maguiblock.com\/wp-content\/uploads\/2024\/10\/Untitled-design-7-150x150.jpg 150w, https:\/\/maguiblock.com\/wp-content\/uploads\/2024\/10\/Untitled-design-7-90x90.jpg 90w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column3448_e235d9-3a > .kt-inside-inner-col,.kadence-column3448_e235d9-3a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3448_e235d9-3a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3448_e235d9-3a > .kt-inside-inner-col{flex-direction:column;}.kadence-column3448_e235d9-3a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3448_e235d9-3a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3448_e235d9-3a{position:relative;}@media all and (max-width: 1024px){.kadence-column3448_e235d9-3a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3448_e235d9-3a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3448_e235d9-3a\"><div class=\"kt-inside-inner-col\">\n<p class=\"has-text-align-center\">3. Contar con la disposici\u00f3n y el valor para resolver los asuntos personales limitantes que deben cambiar en ti para dar sesiones amorosas, profundas y sanadoras.<\/p>\n\n\n<style>.kb-image3448_02f5ac-4f .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image3448_02f5ac-4f size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/maguiblock.com\/wp-content\/uploads\/2024\/10\/Untitled-design-8.jpg\" alt=\"\" class=\"kb-img wp-image-38361\" srcset=\"https:\/\/maguiblock.com\/wp-content\/uploads\/2024\/10\/Untitled-design-8.jpg 600w, https:\/\/maguiblock.com\/wp-content\/uploads\/2024\/10\/Untitled-design-8-300x300.jpg 300w, https:\/\/maguiblock.com\/wp-content\/uploads\/2024\/10\/Untitled-design-8-100x100.jpg 100w, https:\/\/maguiblock.com\/wp-content\/uploads\/2024\/10\/Untitled-design-8-150x150.jpg 150w, https:\/\/maguiblock.com\/wp-content\/uploads\/2024\/10\/Untitled-design-8-90x90.jpg 90w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3448_b221ef-16 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3448_b221ef-16 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3448_b221ef-16 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1100px;margin-left:auto;margin-right:auto;padding-top:60px;padding-bottom:60px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id3448_b221ef-16 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3448_b221ef-16 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id3448_b221ef-16 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3448_b221ef-16 alignnone has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3448_e46459-27 > .kt-inside-inner-col,.kadence-column3448_e46459-27 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3448_e46459-27 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3448_e46459-27 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3448_e46459-27 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3448_e46459-27 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3448_e46459-27{position:relative;}@media all and (max-width: 1024px){.kadence-column3448_e46459-27 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3448_e46459-27 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3448_e46459-27\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns3448_56970c-c3{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns3448_56970c-c3 .kt-button{font-weight:normal;font-style:normal;}.kt-btns3448_56970c-c3 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns3448_56970c-c3 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns3448_56970c-c3 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns3448_56970c-c3 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns3448_56970c-c3 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns3448_56970c-c3 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns3448_56970c-c3 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns3448_56970c-c3\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn3448_d25564-db.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn3448_d25564-db.kb-button{color:var(--global-palette7, #EDF2F7);background:var(--global-palette9, #ffffff);font-size:13px;font-family:Roboto;font-weight:500;text-transform:uppercase;border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;box-shadow:1px 1px 2px 0px rgba(0, 0, 0, 0.2);}.kb-btn3448_d25564-db.kb-button .kb-svg-icon-wrap{color:#87cbb1;padding-bottom:2px;}.wp-block-kadence-advancedbtn .kb-btn3448_d25564-db.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn3448_d25564-db.kb-button:focus{color:var(--global-palette7, #EDF2F7);background:var(--global-palette9, #ffffff);}<\/style><span class=\"kb-button kt-button button kb-btn3448_d25564-db kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill  kt-btn-has-text-true kt-btn-has-svg-true  wp-block-kadence-singlebtn\"><span class=\"kb-svg-icon-wrap kb-svg-icon-ic_record kt-btn-icon-side-left\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M3 0c-1.66 0-3 1.34-3 3s1.34 3 3 3 3-1.34 3-3-1.34-3-3-3z\" transform=\"translate(1 1)\"\/><\/svg><\/span><span class=\"kt-btn-inner-text\"><strong><strong><strong><strong>Diplomado en sistemas familiares<\/strong><\/strong><\/strong><\/strong><\/span><\/span><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3448_b937af-c1, .wp-block-kadence-advancedheading.kt-adv-heading3448_b937af-c1[data-kb-block=\"kb-adv-heading3448_b937af-c1\"]{margin-top:-20px;font-size:36px;font-weight:400;font-style:normal;font-family:Roboto;}.wp-block-kadence-advancedheading.kt-adv-heading3448_b937af-c1 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3448_b937af-c1[data-kb-block=\"kb-adv-heading3448_b937af-c1\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3448_b937af-c1 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3448_b937af-c1[data-kb-block=\"kb-adv-heading3448_b937af-c1\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h1 class=\"kt-adv-heading3448_b937af-c1 wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading3448_b937af-c1\">Incluye seis seminarios<\/h1>\n\n\n\n<p class=\"has-theme-palette-9-color has-text-color has-link-color wp-elements-dbf3ec20e9fdc133ac46eeed8c83a6e1\">Cada seminario es un curso completo en s\u00ed mismo, y desde el primero puedes aplicar lo que has aprendido; transformar\u00e1s con amor d\u00e1ndote sesiones a ti misma(o) y a los dem\u00e1s.<\/p>\n\n\n\n<p class=\"has-theme-palette-9-color has-text-color has-link-color wp-elements-382e5f91fd9ad622dfdb8dfc27d7ef67\">Tambi\u00e9n es posible estudiar solo el que te interese*(aplican restricciones) y decidir despu\u00e9s si deseas concluir el diplomado. Te recomiendo estudiarlo completo en el orden en que se enlistan los seminarios para obtener el mayor beneficio.<\/p>\n\n\n\n<p class=\"has-text-align-right has-theme-palette-9-color has-text-color has-link-color wp-elements-059548757b8db3c5dcca337401e7f639\"><em>*Para tomar el seminario de Constelaciones sist\u00e9micas es necesario haber cursado antes los seminarios de: Sanando la familia, Sanado los sistemas y Habilidades terap\u00e9uticas.<\/em><\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column3448_07f40e-43 > .kt-inside-inner-col{display:flex;}.kadence-column3448_07f40e-43 > .kt-inside-inner-col,.kadence-column3448_07f40e-43 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3448_07f40e-43 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3448_07f40e-43 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column3448_07f40e-43 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column3448_07f40e-43{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3448_07f40e-43{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3448_07f40e-43 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column3448_07f40e-43 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3448_07f40e-43{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column3448_07f40e-43{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3448_07f40e-43{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3448_07f40e-43 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column3448_07f40e-43 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column3448_07f40e-43{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3448_07f40e-43{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3448_07f40e-43 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column3448_07f40e-43 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3448_07f40e-43\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3448_b5f54c-50, .wp-block-kadence-advancedheading.kt-adv-heading3448_b5f54c-50[data-kb-block=\"kb-adv-heading3448_b5f54c-50\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3448_b5f54c-50 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3448_b5f54c-50[data-kb-block=\"kb-adv-heading3448_b5f54c-50\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3448_b5f54c-50 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3448_b5f54c-50[data-kb-block=\"kb-adv-heading3448_b5f54c-50\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h1 class=\"kt-adv-heading3448_b5f54c-50 wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading3448_b5f54c-50\">\u00bfEn qu\u00e9 consiste este diplomado?<\/h1>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items3448_88a5fb-46:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items3448_88a5fb-46 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items3448_88a5fb-46 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items3448_88a5fb-46 .kb-svg-icon-wrap{color:#87cbb1;}.wp-block-kadence-iconlist.kt-svg-icon-list-items3448_88a5fb-46 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items3448_88a5fb-46 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items3448_88a5fb-46 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{color:var(--global-palette9, #ffffff);color:var(--global-palette9, #ffffff);}.kt-svg-icon-list-items3448_88a5fb-46 ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items3448_88a5fb-46 kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-3448_a84319-25 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3448_a84319-25\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_check kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"3\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"20 6 9 17 4 12\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Atrae al amor de tu vida<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3448_501bc4-59 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3448_501bc4-59\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_check kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"3\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"20 6 9 17 4 12\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Sanando la familia<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3448_9e5c9b-30 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3448_9e5c9b-30\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_check kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"3\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"20 6 9 17 4 12\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Sanando los sistemas<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3448_ea7d84-04 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3448_ea7d84-04\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_check kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"3\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"20 6 9 17 4 12\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Habilidades terap\u00e9uticas<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3448_94d66d-ce .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3448_94d66d-ce\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_check kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"3\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"20 6 9 17 4 12\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Constelaciones sist\u00e9micas*<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3448_21352d-05 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3448_21352d-05\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_check kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"3\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"20 6 9 17 4 12\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Maestr\u00eda<\/span><\/li>\n<\/ul><\/div>\n\n\n\n<p class=\"has-theme-palette-9-color has-text-color has-link-color wp-elements-e79aba7419656ce6a0026f1dee981e6e\">Cada seminario es un curso completo en s\u00ed mismo y desde el primero puedes aplicar lo que has aprendido para transformar con amor, d\u00e1ndote sesiones a ti misma(o) y a los dem\u00e1s.<br><a href=\"https:\/\/maguiblock.com\/curso\/atrae-al-amor-de-tu-vida\/\"><\/a><\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3448_25d0e1-d7 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3448_25d0e1-d7 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3448_25d0e1-d7 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1100px;margin-left:auto;margin-right:auto;padding-top:60px;padding-bottom:60px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3448_25d0e1-d7 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3448_25d0e1-d7 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3448_25d0e1-d7 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3448_25d0e1-d7 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3448_d5de0b-07 > .kt-inside-inner-col,.kadence-column3448_d5de0b-07 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3448_d5de0b-07 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3448_d5de0b-07 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3448_d5de0b-07 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3448_d5de0b-07 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3448_d5de0b-07{position:relative;}@media all and (max-width: 1024px){.kadence-column3448_d5de0b-07 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3448_d5de0b-07 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3448_d5de0b-07\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3448_d74835-b8, .wp-block-kadence-advancedheading.kt-adv-heading3448_d74835-b8[data-kb-block=\"kb-adv-heading3448_d74835-b8\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3448_d74835-b8 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3448_d74835-b8[data-kb-block=\"kb-adv-heading3448_d74835-b8\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3448_d74835-b8 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3448_d74835-b8[data-kb-block=\"kb-adv-heading3448_d74835-b8\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h1 class=\"kt-adv-heading3448_d74835-b8 wp-block-kadence-advancedheading has-theme-palette-8-color has-text-color\" data-kb-block=\"kb-adv-heading3448_d74835-b8\">\u00bfC\u00f3mo se imparte el diplomado?<\/h1>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Al inscribirte se genera una cuenta de alumna(o) en la p\u00e1gina web donde tendr\u00e1s acceso al material del diplomado, clases, videos y manuales.<\/li>\n\n\n\n<li>Cada seminario se imparte en 16 horas de clase pregrabadas. En total son 96 horas de clases a las que tendr\u00e1s acceso ilimitado, adem\u00e1s de los videos de preparaci\u00f3n.<\/li>\n\n\n\n<li>Este diplomado es pr\u00e1ctico, te da herramientas para transformarte y evolucionar desde el primer momento.<\/li>\n\n\n\n<li>Podr\u00e1s adquirir la caja con 240 figuras para constelar desde el inicio y es indispensable tenerla para el seminario de Constelaciones Sist\u00e9micas<\/li>\n\n\n\n<li>Al completar el seminario de maestr\u00eda recibir\u00e1s un certificado digital por haber completado el entrenamiento.<\/li>\n\n\n\n<li>Para certificarte como coach y estar en la p\u00e1gina web, debes aprobar la evaluaci\u00f3n individual que se realiza individualmente y por cita.<\/li>\n<\/ul>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3448_d8a32e-b9 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3448_d8a32e-b9 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3448_d8a32e-b9 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1100px;margin-left:auto;margin-right:auto;padding-top:80px;padding-bottom:60px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id3448_d8a32e-b9 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3448_d8a32e-b9 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id3448_d8a32e-b9 > .kt-row-column-wrap{padding-top:20px;padding-right:30px;padding-bottom:20px;padding-left:30px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3448_d8a32e-b9 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3448_5c9acd-18 > .kt-inside-inner-col,.kadence-column3448_5c9acd-18 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3448_5c9acd-18 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3448_5c9acd-18 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3448_5c9acd-18 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3448_5c9acd-18 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3448_5c9acd-18{position:relative;}@media all and (max-width: 1024px){.kadence-column3448_5c9acd-18 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3448_5c9acd-18 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3448_5c9acd-18\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns3448_c2cadd-bd{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns3448_c2cadd-bd .kt-button{font-weight:normal;font-style:normal;}.kt-btns3448_c2cadd-bd .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns3448_c2cadd-bd .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns3448_c2cadd-bd .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns3448_c2cadd-bd .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns3448_c2cadd-bd .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns3448_c2cadd-bd .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns3448_c2cadd-bd .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns3448_c2cadd-bd\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn3448_8a1e61-17.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn3448_8a1e61-17.kb-button{color:var(--global-palette7, #EDF2F7);background:var(--global-palette9, #ffffff);font-size:13px;font-family:Roboto;font-weight:500;text-transform:uppercase;border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;box-shadow:1px 1px 2px 0px rgba(0, 0, 0, 0.2);}.kb-btn3448_8a1e61-17.kb-button .kb-svg-icon-wrap{color:#87cbb1;padding-bottom:2px;}.wp-block-kadence-advancedbtn .kb-btn3448_8a1e61-17.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn3448_8a1e61-17.kb-button:focus{color:var(--global-palette7, #EDF2F7);background:var(--global-palette9, #ffffff);}<\/style><span class=\"kb-button kt-button button kb-btn3448_8a1e61-17 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill  kt-btn-has-text-true kt-btn-has-svg-true  wp-block-kadence-singlebtn\"><span class=\"kb-svg-icon-wrap kb-svg-icon-ic_record kt-btn-icon-side-left\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M3 0c-1.66 0-3 1.34-3 3s1.34 3 3 3 3-1.34 3-3-1.34-3-3-3z\" transform=\"translate(1 1)\"\/><\/svg><\/span><span class=\"kt-btn-inner-text\"><strong><strong>Diplomado en sistemas familiares<\/strong><\/strong><\/span><\/span><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3448_d61c3c-2d, .wp-block-kadence-advancedheading.kt-adv-heading3448_d61c3c-2d[data-kb-block=\"kb-adv-heading3448_d61c3c-2d\"]{margin-top:-20px;font-size:36px;font-weight:400;font-style:normal;font-family:Roboto;}.wp-block-kadence-advancedheading.kt-adv-heading3448_d61c3c-2d mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3448_d61c3c-2d[data-kb-block=\"kb-adv-heading3448_d61c3c-2d\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3448_d61c3c-2d img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3448_d61c3c-2d[data-kb-block=\"kb-adv-heading3448_d61c3c-2d\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading3448_d61c3c-2d wp-block-kadence-advancedheading has-theme-palette-8-color has-text-color\" data-kb-block=\"kb-adv-heading3448_d61c3c-2d\">\u00bfC\u00f3mo funciona?<\/h2>\n\n\n<style>.kt-accordion-id3448_30a88f-11 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:10px;}.kt-accordion-id3448_30a88f-11 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-accordion-id3448_30a88f-11 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:#f2f2f2;border-top-style:solid;border-right-color:#f2f2f2;border-right-style:solid;border-bottom-color:#f2f2f2;border-bottom-style:solid;border-left-color:#f2f2f2;border-left-style:solid;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;background:#f2f2f2;color:var(--global-palette8, #F7FAFC);padding-top:20px;padding-right:14px;padding-bottom:20px;padding-left:30px;}.kt-accordion-id3448_30a88f-11:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3448_30a88f-11:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette7, #EDF2F7);}.kt-accordion-id3448_30a88f-11:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:var(--global-palette7, #EDF2F7);}.kt-accordion-id3448_30a88f-11:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3448_30a88f-11:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:#f2f2f2;}.kt-accordion-id3448_30a88f-11 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id3448_30a88f-11 .kt-blocks-accordion-header:focus-visible{color:var(--global-palette9, #ffffff);background:var(--global-palette7, #EDF2F7);border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id3448_30a88f-11:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3448_30a88f-11:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id3448_30a88f-11:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id3448_30a88f-11:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette9, #ffffff);}.kt-accordion-id3448_30a88f-11:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id3448_30a88f-11:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:var(--global-palette9, #ffffff);}.kt-accordion-id3448_30a88f-11:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3448_30a88f-11:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id3448_30a88f-11:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id3448_30a88f-11:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette7, #EDF2F7);}.kt-accordion-id3448_30a88f-11 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id3448_30a88f-11 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:var(--global-palette9, #ffffff);background:var(--global-palette7, #EDF2F7);border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}.kt-accordion-id3448_30a88f-11:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3448_30a88f-11:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette9, #ffffff);}.kt-accordion-id3448_30a88f-11:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:var(--global-palette9, #ffffff);}.kt-accordion-id3448_30a88f-11:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3448_30a88f-11:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette7, #EDF2F7);}@media all and (max-width: 1024px){.kt-accordion-id3448_30a88f-11 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id3448_30a88f-11 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:#f2f2f2;border-top-style:solid;border-right-color:#f2f2f2;border-right-style:solid;border-bottom-color:#f2f2f2;border-bottom-style:solid;border-left-color:#f2f2f2;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id3448_30a88f-11 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id3448_30a88f-11 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id3448_30a88f-11 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id3448_30a88f-11 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id3448_30a88f-11 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id3448_30a88f-11 .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:10px;}.kt-accordion-id3448_30a88f-11 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}.kt-accordion-id3448_30a88f-11 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:#f2f2f2;border-top-style:solid;border-right-color:#f2f2f2;border-right-style:solid;border-bottom-color:#f2f2f2;border-bottom-style:solid;border-left-color:#f2f2f2;border-left-style:solid;}.kt-accordion-id3448_30a88f-11 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id3448_30a88f-11 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id3448_30a88f-11 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id3448_30a88f-11 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id3448_30a88f-11 kt-accordion-has-27-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-basic kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"0\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-1 kt-pane3448_e930d9-1a\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\"><strong>Materiales<\/strong><\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p>Al inscribirte se genera una cuenta de alumna(o) en la p\u00e1gina web, y con ella tendr\u00e1s acceso al material del diplomado: clases, audios, videos y manuales.<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3448_9470a6-71 > .kt-inside-inner-col{display:flex;}.kadence-column3448_9470a6-71 > .kt-inside-inner-col,.kadence-column3448_9470a6-71 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3448_9470a6-71 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3448_9470a6-71 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column3448_9470a6-71 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column3448_9470a6-71{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3448_9470a6-71{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3448_9470a6-71 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column3448_9470a6-71 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3448_9470a6-71{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column3448_9470a6-71{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3448_9470a6-71{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3448_9470a6-71 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column3448_9470a6-71 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column3448_9470a6-71{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3448_9470a6-71{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3448_9470a6-71 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column3448_9470a6-71 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3448_9470a6-71\"><div class=\"kt-inside-inner-col\"><style>.kb-image3448_45d184-06 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;}.kb-image3448_45d184-06 img.kb-img, .kb-image3448_45d184-06 .kb-img img{border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image3448_45d184-06 size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1006\" src=\"https:\/\/maguiblock.com\/wp-content\/uploads\/2022\/07\/C2.jpg\" alt=\"\" class=\"kb-img wp-image-29277\" srcset=\"https:\/\/maguiblock.com\/wp-content\/uploads\/2022\/07\/C2.jpg 1200w, https:\/\/maguiblock.com\/wp-content\/uploads\/2022\/07\/C2-600x503.jpg 600w, https:\/\/maguiblock.com\/wp-content\/uploads\/2022\/07\/C2-768x644.jpg 768w, https:\/\/maguiblock.com\/wp-content\/uploads\/2022\/07\/C2-1140x956.jpg 1140w, https:\/\/maguiblock.com\/wp-content\/uploads\/2022\/07\/C2-107x90.jpg 107w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3448_52d266-c5 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3448_52d266-c5 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3448_52d266-c5 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1100px;margin-left:auto;margin-right:auto;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3448_52d266-c5 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3448_52d266-c5 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3448_52d266-c5 > .kt-row-column-wrap{padding-right:30px;padding-left:30px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3448_52d266-c5 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3448_3f3edd-3a > .kt-inside-inner-col,.kadence-column3448_3f3edd-3a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3448_3f3edd-3a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3448_3f3edd-3a > .kt-inside-inner-col{flex-direction:column;}.kadence-column3448_3f3edd-3a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3448_3f3edd-3a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3448_3f3edd-3a{position:relative;}@media all and (max-width: 1024px){.kadence-column3448_3f3edd-3a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3448_3f3edd-3a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3448_3f3edd-3a\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3448_b3843a-ea, .wp-block-kadence-advancedheading.kt-adv-heading3448_b3843a-ea[data-kb-block=\"kb-adv-heading3448_b3843a-ea\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3448_b3843a-ea mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3448_b3843a-ea[data-kb-block=\"kb-adv-heading3448_b3843a-ea\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3448_b3843a-ea img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3448_b3843a-ea[data-kb-block=\"kb-adv-heading3448_b3843a-ea\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h1 class=\"kt-adv-heading3448_b3843a-ea wp-block-kadence-advancedheading has-theme-palette-8-color has-text-color\" data-kb-block=\"kb-adv-heading3448_b3843a-ea\">\u00bfCu\u00e1l es la inversi\u00f3n para el Diplomado en Sistemas Familiares?<\/h1>\n\n\n\n<p class=\"has-text-align-center\"><br>Tienes tres opciones de pago: en un solo pago, tres pagos o pagando por seminario.<\/p>\n\n\n<style>.kb-row-layout-id3448_6dabca-d6 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3448_6dabca-d6 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3448_6dabca-d6 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:826px;margin-left:auto;margin-right:auto;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id3448_6dabca-d6 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3448_6dabca-d6 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id3448_6dabca-d6 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3448_6dabca-d6 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3448_591e8e-2d > .kt-inside-inner-col{padding-top:60px;padding-right:20px;padding-bottom:40px;padding-left:20px;}.kadence-column3448_591e8e-2d > .kt-inside-inner-col{box-shadow:0px 0px 14px 0px rgba(0, 0, 0, 0.2);}.kadence-column3448_591e8e-2d > .kt-inside-inner-col,.kadence-column3448_591e8e-2d > .kt-inside-inner-col:before{border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;}.kadence-column3448_591e8e-2d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3448_591e8e-2d > .kt-inside-inner-col{flex-direction:column;}.kadence-column3448_591e8e-2d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3448_591e8e-2d > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column3448_591e8e-2d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3448_591e8e-2d{position:relative;}.kadence-column3448_591e8e-2d, .kt-inside-inner-col > .kadence-column3448_591e8e-2d:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}@media all and (max-width: 1024px){.kadence-column3448_591e8e-2d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3448_591e8e-2d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3448_591e8e-2d\" data-aos=\"fade-right\" data-aos-duration=\"2000\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns3448_695e02-fd{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns3448_695e02-fd .kt-button{font-weight:normal;font-style:normal;}.kt-btns3448_695e02-fd .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns3448_695e02-fd .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns3448_695e02-fd .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns3448_695e02-fd .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns3448_695e02-fd .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns3448_695e02-fd .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns3448_695e02-fd .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns3448_695e02-fd\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn3448_174e06-08.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn3448_174e06-08.kb-button{color:var(--global-palette9, #ffffff);background:#5de47f;font-size:13px;font-family:Roboto;font-weight:500;text-transform:uppercase;border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;box-shadow:1px 1px 2px 0px rgba(0, 0, 0, 0.2);}.kb-btn3448_174e06-08.kb-button .kb-svg-icon-wrap{color:#87cbb1;padding-bottom:2px;}.wp-block-kadence-advancedbtn .kb-btn3448_174e06-08.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn3448_174e06-08.kb-button:focus{color:var(--global-palette7, #EDF2F7);background:var(--global-palette9, #ffffff);}<\/style><span class=\"kb-button kt-button button kb-btn3448_174e06-08 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill  kt-btn-has-text-true kt-btn-has-svg-true  wp-block-kadence-singlebtn\"><span class=\"kb-svg-icon-wrap kb-svg-icon-ic_record kt-btn-icon-side-left\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M3 0c-1.66 0-3 1.34-3 3s1.34 3 3 3 3-1.34 3-3-1.34-3-3-3z\" transform=\"translate(1 1)\"\/><\/svg><\/span><span class=\"kt-btn-inner-text\"><strong>Un solo pago<\/strong><\/span><\/span><\/div>\n\n\n<style>.kb-row-layout-id3448_8ae119-00 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3448_8ae119-00 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3448_8ae119-00 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-bottom:0px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id3448_8ae119-00{border-bottom:1px solid rgba(0,0,0,0);}.kb-row-layout-id3448_8ae119-00 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3448_8ae119-00 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 1024px){.kb-row-layout-id3448_8ae119-00{border-bottom:1px solid rgba(0,0,0,0);}}@media all and (max-width: 767px){.kb-row-layout-id3448_8ae119-00 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id3448_8ae119-00{border-bottom:1px solid rgba(0,0,0,0);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3448_8ae119-00 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-equal kt-row-valign-top\">\n<style>.kadence-column3448_b42c02-53 > .kt-inside-inner-col,.kadence-column3448_b42c02-53 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3448_b42c02-53 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3448_b42c02-53 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3448_b42c02-53 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3448_b42c02-53 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3448_b42c02-53{position:relative;}.kadence-column3448_b42c02-53, .kt-inside-inner-col > .kadence-column3448_b42c02-53:not(.specificity){margin-right:30px;}@media all and (max-width: 1024px){.kadence-column3448_b42c02-53 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3448_b42c02-53 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3448_b42c02-53\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3448_b3aaa8-4a, .wp-block-kadence-advancedheading.kt-adv-heading3448_b3aaa8-4a[data-kb-block=\"kb-adv-heading3448_b3aaa8-4a\"]{text-align:right;font-size:23px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3448_b3aaa8-4a mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3448_b3aaa8-4a[data-kb-block=\"kb-adv-heading3448_b3aaa8-4a\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3448_b3aaa8-4a img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3448_b3aaa8-4a[data-kb-block=\"kb-adv-heading3448_b3aaa8-4a\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading3448_b3aaa8-4a wp-block-kadence-advancedheading has-theme-palette-7-color has-text-color\" data-kb-block=\"kb-adv-heading3448_b3aaa8-4a\"><strong>USD<\/strong><\/h2>\n<\/div><\/div>\n\n\n<style>.kadence-column3448_6ce3a8-f5 > .kt-inside-inner-col,.kadence-column3448_6ce3a8-f5 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3448_6ce3a8-f5 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3448_6ce3a8-f5 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3448_6ce3a8-f5 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3448_6ce3a8-f5 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3448_6ce3a8-f5{position:relative;}.kadence-column3448_6ce3a8-f5, .kt-inside-inner-col > .kadence-column3448_6ce3a8-f5:not(.specificity){margin-left:-30px;}@media all and (max-width: 1024px){.kadence-column3448_6ce3a8-f5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3448_6ce3a8-f5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3448_6ce3a8-f5\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3448_ef85ce-3f, .wp-block-kadence-advancedheading.kt-adv-heading3448_ef85ce-3f[data-kb-block=\"kb-adv-heading3448_ef85ce-3f\"]{margin-left:0px;text-align:left;font-size:42px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3448_ef85ce-3f mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3448_ef85ce-3f[data-kb-block=\"kb-adv-heading3448_ef85ce-3f\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3448_ef85ce-3f img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3448_ef85ce-3f[data-kb-block=\"kb-adv-heading3448_ef85ce-3f\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading3448_ef85ce-3f wp-block-kadence-advancedheading has-theme-palette-7-color has-text-color\" data-kb-block=\"kb-adv-heading3448_ef85ce-3f\"><strong>4,950<\/strong><\/h2>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kadence-column3448_a5ca60-5c > .kt-inside-inner-col{border-bottom:1px solid rgba(0,0,0,0.51);}.kadence-column3448_a5ca60-5c > .kt-inside-inner-col,.kadence-column3448_a5ca60-5c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3448_a5ca60-5c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3448_a5ca60-5c > .kt-inside-inner-col{flex-direction:column;}.kadence-column3448_a5ca60-5c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3448_a5ca60-5c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3448_a5ca60-5c{position:relative;}@media all and (max-width: 1024px){.kadence-column3448_a5ca60-5c > .kt-inside-inner-col{border-bottom:1px solid rgba(0,0,0,0.51);flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3448_a5ca60-5c > .kt-inside-inner-col{border-bottom:1px solid rgba(0,0,0,0.51);flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3448_a5ca60-5c\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3448_b1079d-7c, .wp-block-kadence-advancedheading.kt-adv-heading3448_b1079d-7c[data-kb-block=\"kb-adv-heading3448_b1079d-7c\"]{margin-top:0px;margin-left:0px;text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3448_b1079d-7c mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3448_b1079d-7c[data-kb-block=\"kb-adv-heading3448_b1079d-7c\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3448_b1079d-7c img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3448_b1079d-7c[data-kb-block=\"kb-adv-heading3448_b1079d-7c\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading3448_b1079d-7c wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3448_b1079d-7c\"><\/p>\n<\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kt-btns3448_e015b5-be, .site .entry-content .wp-block-kadence-advancedbtn.kt-btns3448_e015b5-be, .wp-block-kadence-advancedbtn.kb-btns3448_e015b5-be, .site .entry-content .wp-block-kadence-advancedbtn.kb-btns3448_e015b5-be{margin-top:40px;}.wp-block-kadence-advancedbtn.kb-btns3448_e015b5-be{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns3448_e015b5-be .kt-button{font-weight:normal;font-style:normal;}.kt-btns3448_e015b5-be .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns3448_e015b5-be .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns3448_e015b5-be .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns3448_e015b5-be .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns3448_e015b5-be .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns3448_e015b5-be .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns3448_e015b5-be .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns3448_e015b5-be\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn3448_c46b10-13.kb-button{width:initial;}<\/style><a class=\"kb-button kt-button button kb-btn3448_c46b10-13 kt-btn-size-standard kt-btn-width-type-full kb-btn-global-inherit  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-button__link wp-block-kadence-singlebtn\" href=\"https:\/\/maguiblock.com\/?add-to-cart=35036\"><span class=\"kt-btn-inner-text\">COMPRAR<\/span><\/a><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3448_f0f685-79 > .kt-inside-inner-col{padding-top:60px;padding-right:20px;padding-bottom:40px;padding-left:20px;}.kadence-column3448_f0f685-79 > .kt-inside-inner-col{box-shadow:0px 0px 14px 0px rgba(0, 0, 0, 0.2);}.kadence-column3448_f0f685-79 > .kt-inside-inner-col,.kadence-column3448_f0f685-79 > .kt-inside-inner-col:before{border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;}.kadence-column3448_f0f685-79 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3448_f0f685-79 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3448_f0f685-79 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3448_f0f685-79 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column3448_f0f685-79 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3448_f0f685-79{position:relative;}.kadence-column3448_f0f685-79, .kt-inside-inner-col > .kadence-column3448_f0f685-79:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}@media all and (max-width: 1024px){.kadence-column3448_f0f685-79 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3448_f0f685-79 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3448_f0f685-79\" data-aos=\"fade-right\" data-aos-duration=\"2000\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns3448_c8a764-63{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns3448_c8a764-63 .kt-button{font-weight:normal;font-style:normal;}.kt-btns3448_c8a764-63 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns3448_c8a764-63 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns3448_c8a764-63 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns3448_c8a764-63 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns3448_c8a764-63 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns3448_c8a764-63 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns3448_c8a764-63 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns3448_c8a764-63\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn3448_72aace-d7.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn3448_72aace-d7.kb-button{color:var(--global-palette9, #ffffff);background:#5de47f;font-size:13px;font-family:Roboto;font-weight:500;text-transform:uppercase;border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;box-shadow:1px 1px 2px 0px rgba(0, 0, 0, 0.2);}.kb-btn3448_72aace-d7.kb-button .kb-svg-icon-wrap{color:#87cbb1;padding-bottom:2px;}.wp-block-kadence-advancedbtn .kb-btn3448_72aace-d7.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn3448_72aace-d7.kb-button:focus{color:var(--global-palette7, #EDF2F7);background:var(--global-palette9, #ffffff);}<\/style><span class=\"kb-button kt-button button kb-btn3448_72aace-d7 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill  kt-btn-has-text-true kt-btn-has-svg-true  wp-block-kadence-singlebtn\"><span class=\"kb-svg-icon-wrap kb-svg-icon-ic_record kt-btn-icon-side-left\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M3 0c-1.66 0-3 1.34-3 3s1.34 3 3 3 3-1.34 3-3-1.34-3-3-3z\" transform=\"translate(1 1)\"\/><\/svg><\/span><span class=\"kt-btn-inner-text\"><strong>Un solo pago<\/strong><\/span><\/span><\/div>\n\n\n<style>.kb-row-layout-id3448_37f4e5-fd > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3448_37f4e5-fd > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3448_37f4e5-fd > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-bottom:0px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id3448_37f4e5-fd{border-bottom:1px solid rgba(0,0,0,0);}.kb-row-layout-id3448_37f4e5-fd > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3448_37f4e5-fd > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 1024px){.kb-row-layout-id3448_37f4e5-fd{border-bottom:1px solid rgba(0,0,0,0);}}@media all and (max-width: 767px){.kb-row-layout-id3448_37f4e5-fd > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id3448_37f4e5-fd{border-bottom:1px solid rgba(0,0,0,0);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3448_37f4e5-fd alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-equal kt-row-valign-top\">\n<style>.kadence-column3448_7e4db9-bf > .kt-inside-inner-col,.kadence-column3448_7e4db9-bf > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3448_7e4db9-bf > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3448_7e4db9-bf > .kt-inside-inner-col{flex-direction:column;}.kadence-column3448_7e4db9-bf > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3448_7e4db9-bf > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3448_7e4db9-bf{position:relative;}.kadence-column3448_7e4db9-bf, .kt-inside-inner-col > .kadence-column3448_7e4db9-bf:not(.specificity){margin-right:30px;}@media all and (max-width: 1024px){.kadence-column3448_7e4db9-bf > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3448_7e4db9-bf > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3448_7e4db9-bf\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3448_47e589-3e, .wp-block-kadence-advancedheading.kt-adv-heading3448_47e589-3e[data-kb-block=\"kb-adv-heading3448_47e589-3e\"]{text-align:right;font-size:23px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3448_47e589-3e mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3448_47e589-3e[data-kb-block=\"kb-adv-heading3448_47e589-3e\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3448_47e589-3e img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3448_47e589-3e[data-kb-block=\"kb-adv-heading3448_47e589-3e\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading3448_47e589-3e wp-block-kadence-advancedheading has-theme-palette-7-color has-text-color\" data-kb-block=\"kb-adv-heading3448_47e589-3e\"><strong>USD<\/strong><\/h2>\n<\/div><\/div>\n\n\n<style>.kadence-column3448_2f9d02-d9 > .kt-inside-inner-col,.kadence-column3448_2f9d02-d9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3448_2f9d02-d9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3448_2f9d02-d9 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3448_2f9d02-d9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3448_2f9d02-d9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3448_2f9d02-d9{position:relative;}.kadence-column3448_2f9d02-d9, .kt-inside-inner-col > .kadence-column3448_2f9d02-d9:not(.specificity){margin-left:-30px;}@media all and (max-width: 1024px){.kadence-column3448_2f9d02-d9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3448_2f9d02-d9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3448_2f9d02-d9\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3448_1f201f-f9, .wp-block-kadence-advancedheading.kt-adv-heading3448_1f201f-f9[data-kb-block=\"kb-adv-heading3448_1f201f-f9\"]{margin-left:0px;text-align:left;font-size:42px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3448_1f201f-f9 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3448_1f201f-f9[data-kb-block=\"kb-adv-heading3448_1f201f-f9\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3448_1f201f-f9 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3448_1f201f-f9[data-kb-block=\"kb-adv-heading3448_1f201f-f9\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading3448_1f201f-f9 wp-block-kadence-advancedheading has-theme-palette-7-color has-text-color\" data-kb-block=\"kb-adv-heading3448_1f201f-f9\"><strong><strong>950<\/strong><\/strong><\/h2>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kadence-column3448_46f2aa-97 > .kt-inside-inner-col{border-bottom:1px solid rgba(0,0,0,0.51);}.kadence-column3448_46f2aa-97 > .kt-inside-inner-col,.kadence-column3448_46f2aa-97 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3448_46f2aa-97 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3448_46f2aa-97 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3448_46f2aa-97 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3448_46f2aa-97 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3448_46f2aa-97{position:relative;}.kadence-column3448_46f2aa-97, .kt-inside-inner-col > .kadence-column3448_46f2aa-97:not(.specificity){margin-bottom:40px;}@media all and (max-width: 1024px){.kadence-column3448_46f2aa-97 > .kt-inside-inner-col{border-bottom:1px solid rgba(0,0,0,0.51);flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3448_46f2aa-97 > .kt-inside-inner-col{border-bottom:1px solid rgba(0,0,0,0.51);flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3448_46f2aa-97\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3448_6b2846-e0, .wp-block-kadence-advancedheading.kt-adv-heading3448_6b2846-e0[data-kb-block=\"kb-adv-heading3448_6b2846-e0\"]{margin-top:0px;margin-left:0px;text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3448_6b2846-e0 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3448_6b2846-e0[data-kb-block=\"kb-adv-heading3448_6b2846-e0\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3448_6b2846-e0 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3448_6b2846-e0[data-kb-block=\"kb-adv-heading3448_6b2846-e0\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading3448_6b2846-e0 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3448_6b2846-e0\"><strong><strong><strong><strong>cada seminario<\/strong><\/strong><\/strong><\/strong><\/p>\n<\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns3448_9a0394-2c{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns3448_9a0394-2c .kt-button{font-weight:normal;font-style:normal;}.kt-btns3448_9a0394-2c .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns3448_9a0394-2c .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns3448_9a0394-2c .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns3448_9a0394-2c .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns3448_9a0394-2c .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns3448_9a0394-2c .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns3448_9a0394-2c .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns3448_9a0394-2c\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn3448_1d9931-41.kb-button{width:initial;}<\/style><a class=\"kb-button kt-button button kb-btn3448_1d9931-41 kt-btn-size-standard kt-btn-width-type-full kb-btn-global-inherit  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-button__link wp-block-kadence-singlebtn\" href=\"\/seminarios\/\"><span class=\"kt-btn-inner-text\">COMPRAR<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n<p class=\"has-text-align-center\"><\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3448_34eaee-d6 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3448_34eaee-d6 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3448_34eaee-d6 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1100px;margin-left:auto;margin-right:auto;padding-top:60px;padding-bottom:60px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id3448_34eaee-d6 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3448_34eaee-d6 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id3448_34eaee-d6 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3448_34eaee-d6 alignnone has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3448_e56f2f-89 > .kt-inside-inner-col{display:flex;}.kadence-column3448_e56f2f-89 > .kt-inside-inner-col,.kadence-column3448_e56f2f-89 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3448_e56f2f-89 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3448_e56f2f-89 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column3448_e56f2f-89 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column3448_e56f2f-89{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3448_e56f2f-89{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3448_e56f2f-89 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column3448_e56f2f-89 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3448_e56f2f-89{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column3448_e56f2f-89{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3448_e56f2f-89{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3448_e56f2f-89 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column3448_e56f2f-89 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column3448_e56f2f-89{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3448_e56f2f-89{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3448_e56f2f-89 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column3448_e56f2f-89 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3448_e56f2f-89\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3448_8b5557-ef, .wp-block-kadence-advancedheading.kt-adv-heading3448_8b5557-ef[data-kb-block=\"kb-adv-heading3448_8b5557-ef\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3448_8b5557-ef mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3448_8b5557-ef[data-kb-block=\"kb-adv-heading3448_8b5557-ef\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3448_8b5557-ef img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3448_8b5557-ef[data-kb-block=\"kb-adv-heading3448_8b5557-ef\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h1 class=\"kt-adv-heading3448_8b5557-ef wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading3448_8b5557-ef\">Esta inversi\u00f3n no incluye:<\/h1>\n\n\n\n<ul class=\"wp-block-list has-theme-palette-9-color has-text-color has-link-color wp-elements-f33b346c313276d4c165f2c872eae934\">\n<li>La caja de figuras para constelar USD 250 + env\u00edo.<\/li>\n\n\n\n<li>*Incluye 10% de descuento para estudiantes (225 USD)<\/li>\n\n\n\n<li>La evaluaci\u00f3n individual por zoom de una hora y media USD 412 (el coach en proceso de certificaci\u00f3n deber\u00e1 traer su consultante).<\/li>\n<\/ul>\n<\/div><\/div>\n\n\n<style>.kadence-column3448_2d72cd-32 > .kt-inside-inner-col,.kadence-column3448_2d72cd-32 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3448_2d72cd-32 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3448_2d72cd-32 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3448_2d72cd-32 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3448_2d72cd-32 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3448_2d72cd-32{position:relative;}@media all and (max-width: 1024px){.kadence-column3448_2d72cd-32 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3448_2d72cd-32 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3448_2d72cd-32\"><div class=\"kt-inside-inner-col\"><style>.kb-image3448_735aa2-8f.kb-image-is-ratio-size, .kb-image3448_735aa2-8f .kb-image-is-ratio-size{max-width:304px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image3448_735aa2-8f.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image3448_735aa2-8f .kb-image-is-ratio-size{align-self:unset;}.kb-image3448_735aa2-8f figure{max-width:304px;}.kb-image3448_735aa2-8f .image-is-svg, .kb-image3448_735aa2-8f .image-is-svg img{width:100%;}.kb-image3448_735aa2-8f .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;}.kb-image3448_735aa2-8f img.kb-img, .kb-image3448_735aa2-8f .kb-img img{border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;}<\/style>\n<div class=\"wp-block-kadence-image kb-image3448_735aa2-8f\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/maguiblock.com\/wp-content\/uploads\/2024\/10\/Untitled-design-10.jpg\" alt=\"\" class=\"kb-img wp-image-38434\" srcset=\"https:\/\/maguiblock.com\/wp-content\/uploads\/2024\/10\/Untitled-design-10.jpg 600w, https:\/\/maguiblock.com\/wp-content\/uploads\/2024\/10\/Untitled-design-10-300x300.jpg 300w, https:\/\/maguiblock.com\/wp-content\/uploads\/2024\/10\/Untitled-design-10-100x100.jpg 100w, https:\/\/maguiblock.com\/wp-content\/uploads\/2024\/10\/Untitled-design-10-150x150.jpg 150w, https:\/\/maguiblock.com\/wp-content\/uploads\/2024\/10\/Untitled-design-10-90x90.jpg 90w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3448_5c23df-49 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3448_5c23df-49 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3448_5c23df-49 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1100px;margin-left:auto;margin-right:auto;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3448_5c23df-49 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3448_5c23df-49 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3448_5c23df-49 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3448_5c23df-49 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3448_36cfc4-61 > .kt-inside-inner-col,.kadence-column3448_36cfc4-61 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3448_36cfc4-61 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3448_36cfc4-61 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3448_36cfc4-61 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3448_36cfc4-61 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3448_36cfc4-61{position:relative;}@media all and (max-width: 1024px){.kadence-column3448_36cfc4-61 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3448_36cfc4-61 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3448_36cfc4-61\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3448_51d81d-66, .wp-block-kadence-advancedheading.kt-adv-heading3448_51d81d-66[data-kb-block=\"kb-adv-heading3448_51d81d-66\"]{max-width:500px;margin-right:auto;margin-left:auto;text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3448_51d81d-66 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3448_51d81d-66[data-kb-block=\"kb-adv-heading3448_51d81d-66\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3448_51d81d-66 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3448_51d81d-66[data-kb-block=\"kb-adv-heading3448_51d81d-66\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading3448_51d81d-66 wp-block-kadence-advancedheading has-theme-palette-8-color has-text-color\" data-kb-block=\"kb-adv-heading3448_51d81d-66\">Cualquier duda, por favor preg\u00fantanos. \u00a1Es un placer atenderte! Con amor Magui Block<\/h2>\n<\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Diplomado Diplomado en sistemas familiares Convi\u00e9rtete en Coach certificado del m\u00e9todo Magui Block\u00ae \u00a1Hola ser de luz!Te ofrezco el&nbsp;diplomado en&#8230;<\/p>","protected":false},"author":214246893,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"enable","_kad_post_title":"hide","_kad_post_layout":"fullwidth","_kad_post_sidebar_id":"","_kad_post_content_style":"unboxed","_kad_post_vertical_padding":"hide","_kad_post_feature":"hide","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":true,"_kad_post_classname":"","footnotes":""},"class_list":["post-3448","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Diplomado - Magui Block Psicoterap\u00e9uta<\/title>\n<meta name=\"description\" content=\"Diplomado en Sistemas Familiares, con el que aprender\u00e1s el m\u00e9todo Magui Block\u00ae, que incluye las t\u00e9cnicas m\u00e1s avanzadas en psicoterapia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maguiblock.com\/en\/diplomado\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diplomado - Magui Block Psicoterap\u00e9uta\" \/>\n<meta property=\"og:description\" content=\"Diplomado en Sistemas Familiares, con el que aprender\u00e1s el m\u00e9todo Magui Block\u00ae, que incluye las t\u00e9cnicas m\u00e1s avanzadas en psicoterapia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maguiblock.com\/en\/diplomado\/\" \/>\n<meta property=\"og:site_name\" content=\"Magui Block Psicoterap\u00e9uta\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-05T17:46:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/maguiblock.com\/wp-content\/uploads\/2022\/06\/Imagen-Magui-2_1200-x-1006-px.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1006\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maguiblock.com\\\/diplomado\\\/\",\"url\":\"https:\\\/\\\/maguiblock.com\\\/diplomado\\\/\",\"name\":\"Diplomado - Magui Block Psicoterap\u00e9uta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maguiblock.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/maguiblock.com\\\/diplomado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/maguiblock.com\\\/diplomado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maguiblock.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Imagen-Magui-2_1200-x-1006-px.jpg\",\"datePublished\":\"2022-07-21T00:34:56+00:00\",\"dateModified\":\"2026-03-05T17:46:08+00:00\",\"description\":\"Diplomado en Sistemas Familiares, con el que aprender\u00e1s el m\u00e9todo Magui Block\u00ae, que incluye las t\u00e9cnicas m\u00e1s avanzadas en psicoterapia.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maguiblock.com\\\/diplomado\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maguiblock.com\\\/diplomado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/maguiblock.com\\\/diplomado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/maguiblock.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Imagen-Magui-2_1200-x-1006-px.jpg\",\"contentUrl\":\"https:\\\/\\\/maguiblock.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Imagen-Magui-2_1200-x-1006-px.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maguiblock.com\\\/diplomado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/maguiblock.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diplomado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maguiblock.com\\\/#website\",\"url\":\"https:\\\/\\\/maguiblock.com\\\/\",\"name\":\"Magui Block Psicoterap\u00e9uta\",\"description\":\"Transf\u00f3rmate con amor | Constelaciones familiares\",\"publisher\":{\"@id\":\"https:\\\/\\\/maguiblock.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maguiblock.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maguiblock.com\\\/#organization\",\"name\":\"Magui Block Psicoterap\u00e9uta\",\"url\":\"https:\\\/\\\/maguiblock.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/maguiblock.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maguiblock.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo_Magui_color-2.png\",\"contentUrl\":\"https:\\\/\\\/maguiblock.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo_Magui_color-2.png\",\"width\":206,\"height\":67,\"caption\":\"Magui Block Psicoterap\u00e9uta\"},\"image\":{\"@id\":\"https:\\\/\\\/maguiblock.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Diplomado - Magui Block Psicoterap\u00e9uta","description":"Diplomado en Sistemas Familiares, con el que aprender\u00e1s el m\u00e9todo Magui Block\u00ae, que incluye las t\u00e9cnicas m\u00e1s avanzadas en psicoterapia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maguiblock.com\/en\/diplomado\/","og_locale":"en_US","og_type":"article","og_title":"Diplomado - Magui Block Psicoterap\u00e9uta","og_description":"Diplomado en Sistemas Familiares, con el que aprender\u00e1s el m\u00e9todo Magui Block\u00ae, que incluye las t\u00e9cnicas m\u00e1s avanzadas en psicoterapia.","og_url":"https:\/\/maguiblock.com\/en\/diplomado\/","og_site_name":"Magui Block Psicoterap\u00e9uta","article_modified_time":"2026-03-05T17:46:08+00:00","og_image":[{"width":1200,"height":1006,"url":"https:\/\/maguiblock.com\/wp-content\/uploads\/2022\/06\/Imagen-Magui-2_1200-x-1006-px.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/maguiblock.com\/diplomado\/","url":"https:\/\/maguiblock.com\/diplomado\/","name":"Diplomado - Magui Block Psicoterap\u00e9uta","isPartOf":{"@id":"https:\/\/maguiblock.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/maguiblock.com\/diplomado\/#primaryimage"},"image":{"@id":"https:\/\/maguiblock.com\/diplomado\/#primaryimage"},"thumbnailUrl":"https:\/\/maguiblock.com\/wp-content\/uploads\/2022\/06\/Imagen-Magui-2_1200-x-1006-px.jpg","datePublished":"2022-07-21T00:34:56+00:00","dateModified":"2026-03-05T17:46:08+00:00","description":"Diplomado en Sistemas Familiares, con el que aprender\u00e1s el m\u00e9todo Magui Block\u00ae, que incluye las t\u00e9cnicas m\u00e1s avanzadas en psicoterapia.","breadcrumb":{"@id":"https:\/\/maguiblock.com\/diplomado\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maguiblock.com\/diplomado\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/maguiblock.com\/diplomado\/#primaryimage","url":"https:\/\/maguiblock.com\/wp-content\/uploads\/2022\/06\/Imagen-Magui-2_1200-x-1006-px.jpg","contentUrl":"https:\/\/maguiblock.com\/wp-content\/uploads\/2022\/06\/Imagen-Magui-2_1200-x-1006-px.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/maguiblock.com\/diplomado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/maguiblock.com\/"},{"@type":"ListItem","position":2,"name":"Diplomado"}]},{"@type":"WebSite","@id":"https:\/\/maguiblock.com\/#website","url":"https:\/\/maguiblock.com\/","name":"Magui Block Psicoterap\u00e9uta","description":"Transf\u00f3rmate con amor | Constelaciones familiares","publisher":{"@id":"https:\/\/maguiblock.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maguiblock.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/maguiblock.com\/#organization","name":"Magui Block Psicoterap\u00e9uta","url":"https:\/\/maguiblock.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/maguiblock.com\/#\/schema\/logo\/image\/","url":"https:\/\/maguiblock.com\/wp-content\/uploads\/2026\/01\/Logo_Magui_color-2.png","contentUrl":"https:\/\/maguiblock.com\/wp-content\/uploads\/2026\/01\/Logo_Magui_color-2.png","width":206,"height":67,"caption":"Magui Block Psicoterap\u00e9uta"},"image":{"@id":"https:\/\/maguiblock.com\/#\/schema\/logo\/image\/"}}]}},"featured_image_src_large":false,"author_info":{"display_name":"Magui Block","author_link":"https:\/\/maguiblock.com\/en\/author\/carinmblock\/"},"comment_info":0,"taxonomy_info":[],"_links":{"self":[{"href":"https:\/\/maguiblock.com\/en\/wp-json\/wp\/v2\/pages\/3448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maguiblock.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/maguiblock.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/maguiblock.com\/en\/wp-json\/wp\/v2\/users\/214246893"}],"replies":[{"embeddable":true,"href":"https:\/\/maguiblock.com\/en\/wp-json\/wp\/v2\/comments?post=3448"}],"version-history":[{"count":176,"href":"https:\/\/maguiblock.com\/en\/wp-json\/wp\/v2\/pages\/3448\/revisions"}],"predecessor-version":[{"id":40619,"href":"https:\/\/maguiblock.com\/en\/wp-json\/wp\/v2\/pages\/3448\/revisions\/40619"}],"wp:attachment":[{"href":"https:\/\/maguiblock.com\/en\/wp-json\/wp\/v2\/media?parent=3448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}